{"id":47485,"date":"2025-04-18T12:26:02","date_gmt":"2025-04-18T12:26:02","guid":{"rendered":"http:\/\/38.242.230.232\/~portoalities\/?p=47485"},"modified":"2025-04-27T14:29:32","modified_gmt":"2025-04-27T14:29:32","slug":"tramway-a-porto-comment-voyager","status":"publish","type":"post","link":"https:\/\/portoalities.com\/fr\/tramway-a-porto-comment-voyager\/","title":{"rendered":"Comment voyager en tramway \u00e0 Porto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;une des choses \u00e0 faire \u00e0 Porto est de prendre le tramway historique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a trois lignes de tramway \u00e0 Porto, et dans cet article vous trouverez non seulement le trajet de chaque ligne de tramway, mais aussi ses horaires, o\u00f9 acheter les billets de tramway, etc. J&rsquo;esp\u00e8re que vous appr\u00e9cierez ce guide sur la fa\u00e7on de voyager en tramway !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Est-ce une bonne id\u00e9e de voyager en tramway \u00e0 Porto&nbsp;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 mon avis, et pour \u00eatre tout \u00e0 fait honn\u00eate, non. Les tramways de Porto sont toujours bond\u00e9s. Vous devrez faire la queue pendant longtemps, et vous serez ensuite coinc\u00e9s comme des sardines dans une bo\u00eete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous cherchez d&rsquo;autres moyens amusants de vous d\u00e9placer \u00e0 Porto, voici mes suggestions&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visites en v\u00e9lo \u00e9lectrique&nbsp;: <a href=\"https:\/\/www.getyourguide.com\/porto-l151\/porto-highlights-e-bike-tour-t181475\/?partner_id=H93B56T&amp;utm_medium=online_publisher&amp;cmp=tramway-a-porto\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">Visite guid\u00e9e de 3h des points forts de la ville en v\u00e9lo \u00e9lectrique<\/a><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visites en tuk-tuk\u00a0: <a href=\"https:\/\/www.getyourguide.com\/porto-l151\/porto-guided-tour-by-tuk-tuk-and-douro-river-cruise-t415204\/?partner_id=H93B56T&amp;utm_medium=online_publisher&amp;cmp=tramway-a-porto\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">Visite guid\u00e9e en tuk-tuk et croisi\u00e8re sur le Douro<\/a><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visites en Segway&nbsp;: <a href=\"https:\/\/www.getyourguide.com\/porto-l151\/original-segway-tour-in-porto-t30740\/?partner_id=H93B56T&amp;cmp=tramway-a-porto\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">Visite de Porto en Segway de 3&nbsp;heures<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment fonctionne le tramway \u00e0 Porto<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"575\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/eglise-trajet-tram-porto.jpeg\" alt=\"eglise trajet tram porto\" class=\"wp-image-47492\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/eglise-trajet-tram-porto.jpeg 778w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/eglise-trajet-tram-porto-300x222.jpeg 300w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/eglise-trajet-tram-porto-768x568.jpeg 768w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Croyez-le ou non, le tramway de Porto est l&rsquo;un des plus anciens syst\u00e8mes de transport \u00e9lectrifi\u00e9 d&rsquo;Europe, puisqu&rsquo;il a \u00e9t\u00e9 inaugur\u00e9 en 1895.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;\u00e9tait un transport tr\u00e8s populaire, mais depuis les ann\u00e9es 60, il a \u00e9t\u00e9 lentement abandonn\u00e9 par les habitants, qui pr\u00e9f\u00e8rent utiliser des moyens de transport plus rapides dans leur vie quotidienne. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, il n&rsquo;y a que trois lignes de tramway , qui sont principalement utilis\u00e9es par les touristes et par quelques locaux. N\u00e9anmoins, faire un tour en tramway \u00e0 Porto est une bonne id\u00e9e pour les&nbsp;familles avec enfants, ou simplement pour faire un tour dans le pass\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les lignes de tramway \u00e0 Porto<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Ligne de tramway 1 : De Ribeira \u00e0 Foz<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La ligne 1 du tramway \u00e0 Porto est la plus connue des touristes, car son trajet longe le fleuve entre&nbsp;le quartier de Ribeira&nbsp;et l&#8217;embouchure du fleuve Douro, dans le&nbsp;quartier de Foz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La promenade commence \u00e0 l&rsquo;arr\u00eat Infante, en face de l&rsquo;\u00e9glise S\u00e3o Francisco, et se termine \u00e0 l&rsquo;arr\u00eat Passeio Alegre, dans les magnifiques jardins de Passeio Alegre. Mais, naturellement, vous pouvez entrer et sortir \u00e0 n&rsquo;importe quel arr\u00eat en cours de route.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le trajet est court &#8211; environ 20 minutes, s&rsquo;il n&rsquo;y a pas d&rsquo;interruptions majeures (comme des voitures qui traversent la ligne), mais tr\u00e8s beau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Conseil local : il y a toujours des files d&rsquo;attente de dizaines de personnes pour prendre la ligne 1 du tramway \u00e0 Porto, je vous recommande donc d&rsquo;y aller le matin, le plus t\u00f4t possible.<\/em><em> Une autre option \u00e0 laquelle personne ne pense est de prendre le tramway dans l&rsquo;autre sens, \u00e0 partir du Passeio Alegre, car il y a g\u00e9n\u00e9ralement beaucoup moins de monde.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Comme il s&rsquo;agit d&rsquo;un tramway tr\u00e8s populaire \u00e0 Porto, vous devez prendre le tramway au premier arr\u00eat, juste devant l&rsquo;\u00e9glise S\u00e3o Francisco, ou au dernier, au Passeio.<\/em> <em>Si vous essayez de prendre le tramway 1 \u00e0 n&rsquo;importe quel autre arr\u00eat, surtout en haute saison, la probabilit\u00e9 de ne pas avoir de place est tr\u00e8s \u00e9lev\u00e9e !<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">V\u00e9rifiez la trajectoire de la ligne 1 du tramway \u00e0 Porto :<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"261\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-1-tramway-porto-ribeira-foz.jpeg\" alt=\"route ligne 1 tramway porto ribeira foz\" class=\"wp-image-47497\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-1-tramway-porto-ribeira-foz.jpeg 705w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-1-tramway-porto-ribeira-foz-300x111.jpeg 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Voici les horaires dans le sens Infante &#8211; Passeio Alegre, tous les jours de la semaine&nbsp;:<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"505\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-infante-passeio-alegre.png\" alt=\"horaire ligne 1 tram porto infante passeio alegre\" class=\"wp-image-47493\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-infante-passeio-alegre.png 668w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-infante-passeio-alegre-300x227.png 300w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Horaires dans le sens Passeio Alegre &#8211; Infante (\u00e0 Ribeira) tous les jours de la semaine :<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"495\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-passeio-alegre-infante.png\" alt=\"horaire ligne 1 tram porto passeio alegre infante\" class=\"wp-image-47494\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-passeio-alegre-infante.png 668w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-1-tram-porto-passeio-alegre-infante-300x222.png 300w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est une excellente option pour se rendre du centre-ville au bord du fleuve, et vous pouvez essayer les activit\u00e9s disponibles sur les rives du fleuve Douro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez, par exemple, prendre le tramway \u00e0 Passeio Alegre et descendre \u00e0 l&rsquo;arr\u00eat Infante, en face de l&rsquo;\u00e9glise Saint-Fran\u00e7ois. Ensuite, descendez au bord du fleuve (cela prend 5 minutes) et prenez la&nbsp;Croisi\u00e8re des 6 ponts, la c\u00e9l\u00e8bre promenade en bateau qui vous offre une vue imprenable sur la ville, et sur les ponts de Porto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme il s&rsquo;agit d&rsquo;une activit\u00e9 tr\u00e8s populaire, je vous recommande d&rsquo;acheter votre&nbsp;<a href=\"https:\/\/www.getyourguide.fr\/porto-l151\/douro-river-six-bridges-cruise-t64873\/?partner_id=H93B56T&amp;cmp=tramway-a-porto\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">billet en ligne pour la Croisi\u00e8re des 6 Ponts<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"469\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/croisiere-six-points-douro-porto.jpeg\" alt=\"croisiere six points douro porto\" class=\"wp-image-47501\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/croisiere-six-points-douro-porto.jpeg 668w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/croisiere-six-points-douro-porto-300x211.jpeg 300w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Une autre option consiste \u00e0 visiter le mus\u00e9e du Monde des D\u00e9couvertes, adapt\u00e9 aux familles avec enfants. Le billet en vente directe est plus cher que le billet en ligne, je vous recommande donc d&rsquo;acheter le&nbsp;<a href=\"https:\/\/www.getyourguide.fr\/porto-l151\/skip-the-line-world-of-discoveries-entrance-ticket-t60149\/?partner_id=H93B56T&amp;cmp=tramway-a-porto\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">billet en ligne pour le Monde des D\u00e9couvertes<\/a>. Vous pouvez ensuite prendre le tramway \u00e0 l&rsquo;arr\u00eat situ\u00e9 pr\u00e8s du Monde des d\u00e9couvertes : tournez le dos au mus\u00e9e et marchez pendant 5 minutes sur votre droite. L&rsquo;arr\u00eat s&rsquo;appelle Alf\u00e2ndega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Conseil local : Comme la plupart des gens prennent le tramway 1 au premier arr\u00eat, lorsqu&rsquo;il arrive \u00e0 l&rsquo;arr\u00eat Alf\u00e2ndega, il est d\u00e9j\u00e0 plein. Vous pouvez donc faire le chemin inverse : prenez le tramway 1 au bout de la ligne, \u00e0 Passeio Alegre, et faites le trajet vers le centre de Porto, puis descendez \u00e0 Alf\u00e2ndega pour visiter le Monde des D\u00e9couvertes.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ligne de tramway 18 : Aller-retour entre Massarelos et Carmo<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La ligne 18 est une ligne de tramway circulaire qui part du Mus\u00e9e du tramway, au bord du fleuve, et qui monte jusqu&rsquo;\u00e0 la tour de Cl\u00e9rigos &#8211; une zone centrale pour ceux qui visitent Porto, puisqu&rsquo;elle est proche de la&nbsp;<a href=\"https:\/\/portoalities.com\/fr\/librairie-lello-a-porto\/\">c\u00e9l\u00e8bre librairie Lello<\/a>&nbsp;et du&nbsp;quartier de la vie nocturne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle se dirige ensuite vers le sud, vers le fleuve Douro, en s&rsquo;arr\u00eatant devant le mus\u00e9e du tramway (qui est une merveille&nbsp;!).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ligne 18 du tramway \u00e0 Porto a l&rsquo;avantage de ne pas \u00eatre une ligne tr\u00e8s pris\u00e9e par les touristes, elle est donc g\u00e9n\u00e9ralement moins fr\u00e9quent\u00e9e. Dans tous les cas, attendez-vous \u00e0 trouver quelques personnes faisant la queue au premier arr\u00eat, \u00e0 Jardim da Cordoaria, juste en face du Caf\u00e9 Piolho.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Voici le trajet de la ligne 18 du tramway \u00e0 Porto :<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"359\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo.jpeg\" alt=\"route ligne 18 tramway porto massarelos carmo\" class=\"wp-image-47498\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo.jpeg 705w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo-300x153.jpeg 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Voici les horaires de la ligne 18 du tramway \u00e0 Porto, tous les jours de la semaine.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Comme il s&rsquo;agit d&rsquo;un voyage aller-retour, il n&rsquo;y a que cet horaire.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"359\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo.jpeg\" alt=\"route ligne 18 tramway porto massarelos carmo\" class=\"wp-image-47498\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo.jpeg 705w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-18-tramway-porto-massarelos-carmo-300x153.jpeg 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ligne de tramway 22<\/strong>: <strong>Aller-retour entre<\/strong> Carmo et Batalha<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Cette ligne de tramway est actuellement ferm\u00e9e en raison de travaux de construction en cours sur l&rsquo;Avenida dos Aliados.<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ligne de tramway 22 est une ligne circulaire qui part de la place Gomes Teixeira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est peut-\u00eatre le tramway le moins connu de Porto mais c&rsquo;est mon pr\u00e9f\u00e9r\u00e9, car il circule non seulement dans le quartier de Cl\u00e9rigos, mais aussi sur l&rsquo;Avenida dos Aliados (l&rsquo;avenue la plus importante de Porto), puis devant la c\u00e9l\u00e8bre&nbsp;Gare de S\u00e3o Bento&nbsp;et enfin sur la&nbsp;Place Batalha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois \u00e0 Batalha, si vous avez ce billet combin\u00e9, vous pouvez emprunter le&nbsp;Funiculaire des Guindais , un ancien ascenseur qui fonctionne depuis 1879. C&rsquo;est une excursion courte mais tr\u00e8s amusante, notamment parce qu&rsquo;elle offre une vue tr\u00e8s inhabituelle sur le pont Luiz I.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Voici le trajet de la ligne 22 du tramway \u00e0 Porto :<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Cette ligne de tramway est actuellement ferm\u00e9e en raison de travaux de construction en cours sur l&rsquo;Avenida dos Aliados.<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"354\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-22-tramway-porto-carmo-batalha.jpeg\" alt=\"route ligne 22 tramway porto carmo batalha\" class=\"wp-image-47499\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-22-tramway-porto-carmo-batalha.jpeg 705w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/route-ligne-22-tramway-porto-carmo-batalha-300x151.jpeg 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Voici les horaires de ce tramway \u00e0 Porto, tous les jours de la semaine :<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Cette ligne de tramway est actuellement ferm\u00e9e en raison de travaux de construction en cours sur l&rsquo;Avenida dos Aliados.<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"479\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-22-tramway-porto.png\" alt=\"horaire ligne 22 tramway porto\" class=\"wp-image-47496\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-22-tramway-porto.png 668w, https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/horaire-ligne-22-tramway-porto-300x215.png 300w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Prix du tramway \u00e0 Porto<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voici les billets disponibles :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prix du tramway \u00e0 Porto pour ADULTES<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1 d\u00e9placement : 6\u20ac<\/li>\n\n\n\n<li>2 sorties dans la m\u00eame journ\u00e9e : 8\u20ac<\/li>\n\n\n\n<li>2 Jours adulte : 12\u20ac<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Prix du tramway \u00e0 Porto pour ENFANTS<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1 d\u00e9placement : 3,50\u20ac<\/li>\n\n\n\n<li>2 Jours enfant (4 \u00e0 12 ans) : 6\u20ac<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">O\u00f9 puis-je acheter les billets ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les billets pour le tramway \u00e0 Porto peuvent \u00eatre achet\u00e9s aux endroits suivants :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Les trams<br>&#8211; Les h\u00f4tels (billets de 2 jours uniquement)<br>&#8211; Les agences de voyage (billets de 2 jours uniquement)<br>&#8211; Certains kiosques (billets de 2 jours uniquement)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dois-je acheter un nouveau billet si je descends du tramway puis que je remonte ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oui. Chaque mont\u00e9e \u00e0 bord du tramway est consid\u00e9r\u00e9e comme un trajet distinct, m\u00eame si vous remontez seulement cinq minutes plus tard.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quels sont les horaires du tramway ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les tramways de Porto circulent tous les jours de 9h \u00e0 21h (dans le cas de la ligne 1) et de 9h45 \u00e0 19h (dans le cas de la ligne 18). En hiver, le dernier trajet au d\u00e9part de Passeio Alegre a lieu \u00e0 19h10 et commence \u00e0 Massarelos \u00e0 19h45, et le dernier trajet de la journ\u00e9e sur la ligne 18 commence \u00e0 18h45.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien entendu, les tramways ne circulent pas le jour de No\u00ebl (24 et 25 d\u00e9cembre) ni le premier jour de l&rsquo;ann\u00e9e, le 1er janvier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Existe-t-il un moyen d&rsquo;\u00e9viter les files d&rsquo;attente devant les tramways ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9tant l\u2019une des activit\u00e9s les plus populaires de Porto, vous devrez probablement faire la queue pendant longtemps. Chaque v\u00e9hicule ne peut accueillir qu&rsquo;un nombre tr\u00e8s limit\u00e9 de personnes, qui voyageront n\u00e9anmoins comme des sardines en conserve dans le tramway. De plus, les files d&rsquo;attente pour les tramways de Porto sont g\u00e9n\u00e9ralement \u00e9normes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a essentiellement deux choses que vous pouvez faire pour \u00e9viter les files d\u2019attente&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">vous pouvez voyager pendant la basse saison, c&rsquo;est-\u00e0-dire de la deuxi\u00e8me quinzaine d&rsquo;octobre jusqu&rsquo;\u00e0 P\u00e2ques, en avril. Donc en gros vous avez 6 mois pendant lesquels la ville n\u2019est pas totalement envahie par les touristes !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">vous pouvez emprunter les lignes de tramway qui sont l\u00e9g\u00e8rement moins populaires que la ligne 1, c&rsquo;est-\u00e0-dire les lignes 18 et 22.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Enregistrez cet article pour plus tard&nbsp;:<\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"325\" height=\"488\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/ildefonso-church-tram-porto.jpg\" alt=\"ildefonso church tram porto\" class=\"wp-image-37248\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/ildefonso-church-tram-porto.jpg 325w, https:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/ildefonso-church-tram-porto-200x300.jpg 200w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"325\" height=\"487\" src=\"http:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/how-to-travel-by-tram-in-porto-pinterest-board.jpg\" alt=\"how travel tram porto pinterest board\" class=\"wp-image-37247\" srcset=\"https:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/how-to-travel-by-tram-in-porto-pinterest-board.jpg 325w, https:\/\/portoalities.com\/wp-content\/uploads\/2019\/12\/how-to-travel-by-tram-in-porto-pinterest-board-200x300.jpg 200w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;une des choses \u00e0 faire \u00e0 Porto est de prendre le tramway historique. Il y a trois lignes de tramway\u2026<\/p>\n","protected":false},"author":3,"featured_media":47682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5002,5114],"tags":[5064,5066,5025],"class_list":["post-47485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attractions-touristiques","category-informations-essentielles-voyager-porto","tag-tram","tag-tramway","tag-transport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities<\/title>\n<meta name=\"description\" content=\"Apprenez tout sur l&#039;utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities\" \/>\n<meta property=\"og:description\" content=\"Apprenez tout sur l&#039;utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/\" \/>\n<meta property=\"og:site_name\" content=\"Portoalities: Travel blog and Private tours in Porto and Douro Valley\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T12:26:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-27T14:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sara Riobom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara Riobom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/\"},\"author\":{\"name\":\"Sara Riobom\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/#\\\/schema\\\/person\\\/86e9ed8d9d1bb211cc9bf16ab54c5c0d\"},\"headline\":\"Comment voyager en tramway \u00e0 Porto\",\"datePublished\":\"2025-04-18T12:26:02+00:00\",\"dateModified\":\"2025-04-27T14:29:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/\"},\"wordCount\":1624,\"image\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portoalities.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/comment-voyager-tramway-a-Porto-1.jpg\",\"keywords\":[\"tram\",\"tramway\",\"transport\"],\"articleSection\":[\"Attractions touristiques\",\"Informations Essentielles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/\",\"url\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/\",\"name\":\"Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portoalities.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/comment-voyager-tramway-a-Porto-1.jpg\",\"datePublished\":\"2025-04-18T12:26:02+00:00\",\"dateModified\":\"2025-04-27T14:29:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/#\\\/schema\\\/person\\\/86e9ed8d9d1bb211cc9bf16ab54c5c0d\"},\"description\":\"Apprenez tout sur l'utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portoalities.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/comment-voyager-tramway-a-Porto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/portoalities.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/comment-voyager-tramway-a-Porto-1.jpg\",\"width\":1440,\"height\":700,\"caption\":\"comment voyager tramway a Porto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/how-to-travel-by-tram-in-porto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portoalities.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment voyager en tramway \u00e0 Porto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/portoalities.com\\\/en\\\/\",\"name\":\"Portoalities: Travel blog and Private tours in Porto and Douro Valley\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portoalities.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portoalities.com\\\/en\\\/#\\\/schema\\\/person\\\/86e9ed8d9d1bb211cc9bf16ab54c5c0d\",\"name\":\"Sara Riobom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g\",\"caption\":\"Sara Riobom\"},\"url\":\"https:\\\/\\\/portoalities.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities","description":"Apprenez tout sur l'utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/","og_locale":"fr_FR","og_type":"article","og_title":"Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities","og_description":"Apprenez tout sur l'utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.","og_url":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/","og_site_name":"Portoalities: Travel blog and Private tours in Porto and Douro Valley","article_published_time":"2025-04-18T12:26:02+00:00","article_modified_time":"2025-04-27T14:29:32+00:00","og_image":[{"width":1440,"height":700,"url":"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg","type":"image\/jpeg"}],"author":"Sara Riobom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sara Riobom","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#article","isPartOf":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/"},"author":{"name":"Sara Riobom","@id":"https:\/\/portoalities.com\/en\/#\/schema\/person\/86e9ed8d9d1bb211cc9bf16ab54c5c0d"},"headline":"Comment voyager en tramway \u00e0 Porto","datePublished":"2025-04-18T12:26:02+00:00","dateModified":"2025-04-27T14:29:32+00:00","mainEntityOfPage":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/"},"wordCount":1624,"image":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#primaryimage"},"thumbnailUrl":"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg","keywords":["tram","tramway","transport"],"articleSection":["Attractions touristiques","Informations Essentielles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/","url":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/","name":"Tramway \u00e0 Porto : D\u00e9couvrez comment voyager | Blog Portoalities","isPartOf":{"@id":"https:\/\/portoalities.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#primaryimage"},"image":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#primaryimage"},"thumbnailUrl":"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg","datePublished":"2025-04-18T12:26:02+00:00","dateModified":"2025-04-27T14:29:32+00:00","author":{"@id":"https:\/\/portoalities.com\/en\/#\/schema\/person\/86e9ed8d9d1bb211cc9bf16ab54c5c0d"},"description":"Apprenez tout sur l'utilisation du tramway \u00e0 Porto : lignes et horaires de tramway, tarifs et o\u00f9 obtenir vos billets de tramway.","breadcrumb":{"@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#primaryimage","url":"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg","contentUrl":"https:\/\/portoalities.com\/wp-content\/uploads\/2021\/10\/comment-voyager-tramway-a-Porto-1.jpg","width":1440,"height":700,"caption":"comment voyager tramway a Porto"},{"@type":"BreadcrumbList","@id":"https:\/\/portoalities.com\/en\/how-to-travel-by-tram-in-porto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portoalities.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment voyager en tramway \u00e0 Porto"}]},{"@type":"WebSite","@id":"https:\/\/portoalities.com\/en\/#website","url":"https:\/\/portoalities.com\/en\/","name":"Portoalities: Travel blog and Private tours in Porto and Douro Valley","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portoalities.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/portoalities.com\/en\/#\/schema\/person\/86e9ed8d9d1bb211cc9bf16ab54c5c0d","name":"Sara Riobom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21142310e9611a432e3b525f3a98f5c0539be889e67ec3fb511c335b41fb3c6a?s=96&d=mm&r=g","caption":"Sara Riobom"},"url":"https:\/\/portoalities.com\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/posts\/47485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/comments?post=47485"}],"version-history":[{"count":0,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/posts\/47485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/media\/47682"}],"wp:attachment":[{"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/media?parent=47485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/categories?post=47485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portoalities.com\/fr\/wp-json\/wp\/v2\/tags?post=47485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}